﻿{"id":2828,"date":"2020-09-28T11:43:18","date_gmt":"2020-09-28T15:43:18","guid":{"rendered":"http:\/\/sites.muscogee.k12.ga.us\/richards\/?p=2828"},"modified":"2020-09-28T13:51:55","modified_gmt":"2020-09-28T17:51:55","slug":"warrior-weekly-9-27-2020","status":"publish","type":"post","link":"https:\/\/sites.muscogee.k12.ga.us\/richards\/2020\/09\/28\/warrior-weekly-9-27-2020\/","title":{"rendered":"Warrior Weekly 9.27.2020"},"content":{"rendered":"<a href=\"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-content\/uploads\/sites\/76\/2020\/09\/Warrior-Weekly-9.27.2020.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">Warrior Weekly 9.27.2020<\/a>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":167,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8,7],"tags":[],"class_list":["post-2828","post","type-post","status-publish","format-standard","hentry","category-upcoming-events","category-warrior-weekly"],"_links":{"self":[{"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/posts\/2828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/users\/167"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/comments?post=2828"}],"version-history":[{"count":2,"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/posts\/2828\/revisions"}],"predecessor-version":[{"id":2830,"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/posts\/2828\/revisions\/2830"}],"wp:attachment":[{"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/media?parent=2828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/categories?post=2828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.muscogee.k12.ga.us\/richards\/wp-json\/wp\/v2\/tags?post=2828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}